{"id":7560,"date":"2022-02-24T10:00:56","date_gmt":"2022-02-24T09:00:56","guid":{"rendered":"https:\/\/pastisserialapalma.com\/?p=7560"},"modified":"2022-02-24T10:00:56","modified_gmt":"2022-02-24T09:00:56","slug":"como-nacio-el-bombon","status":"publish","type":"post","link":"https:\/\/pastisserialapalma.com\/cat\/como-nacio-el-bombon\/","title":{"rendered":"\u00bfC\u00f3mo naci\u00f3 el bomb\u00f3n?"},"content":{"rendered":"<p>La primera vez que se comercializ\u00f3 el bomb\u00f3n fue en 1868 de la mano de Chocolates Cadbury, una marca brit\u00e1nica. Pero la historia apunta a que su origen se remonta a mucho antes.<\/p>\n<p>\u00bfQuieres saber m\u00e1s sobre c\u00f3mo ha llegado a nuestros d\u00edas este dulce tan caracter\u00edstico? Contin\u00faa leyendo el art\u00edculo hasta el final para saber la respuesta.El origen del bomb\u00f3nSeg\u00fan dicta la tradici\u00f3n, aunque se comercializ\u00f3 en en el siglo XIX su origen se remonta al siglo anterior. Todo parece indicar que el <strong>rey Luis XIV de Francia fue el primero en probar esta delicia gracias a su maestro pastelero<\/strong>. En un principio, se bas\u00f3 en una selecci\u00f3n de frutas ba\u00f1adas en chocolate.<\/p>\n<p>Despu\u00e9s de dar el primer bocado, el monarca exclam\u00f3: <strong>\u201cbon, bon!\u201d<\/strong>, que en franc\u00e9s significa <strong>\u201c\u00a1bueno, bueno!\u201d<\/strong>, indicando su aprecio por el dulce.<img decoding=\"async\" src=\"https:\/\/pastisserialapalma.com\/wp-content\/uploads\/como-nacio-el-bombon.jpg\" alt=\"\" \/><br \/>\nAunque no sabemos cu\u00e1nto de cierto hay o no en esta historia, lo que s\u00ed podemos asegurar es que fue un \u00e9xito que tard\u00f3 tiempo en popularizarse.<\/p>\n<p>A partir del siglo XX, dej\u00f3 de tratarse de un dulce exclusivo de Europa y se abri\u00f3 paso en el mercado estadounidense, donde aument\u00f3 su fama. Pero fueron los maestros pasteleros de Europa los que continuaron perfeccionando t\u00e9cnicas de pasteler\u00eda a la luz de las \u00faltimas vanguardias culinarias.<\/p>\n<p>Ahora hay <strong>multitud de sabores disponibles y cada cual se adapta a los gustos de su consumidor<\/strong>. Podemos encontrar variedad en frutos secos, como pistachos, almendras o avellanas\u2026 Tambi\u00e9n se ha introducido la adici\u00f3n de licores. Los chocolates pueden variar en amargor, composici\u00f3n y origen del cacao\u2026 y un largo etc\u00e9tera de variables posibles.<\/p>\n<p>En Pastisseria La Palma realizamos <a href=\"\/cat\/es\/producto\/bombones-artesanos\/\">bombones artesanales<\/a>. Cuidamos el detalle en las materias primas que empleamos, en las t\u00e9cnicas pasteleras y en la presentaci\u00f3n, para que puedas regalarlos en una cajita a tus seres amados o ti mismo. (Pincha en este link para leer el <a href=\"\/cat\/?p=5668\">art\u00edculo recomendado acerca del souvenir gastron\u00f3mico<\/a>).<\/p>\n<p>Cont\u00e1ctanos para hacer tu reserva de bombones.<\/p>\n<p>Contacte<\/p>","protected":false},"excerpt":{"rendered":"<p>La primera vez que se comercializ\u00f3 el bomb\u00f3n fue en 1868 de la mano de Chocolates Cadbury, una marca brit\u00e1nica. Pero la historia apunta a que su origen se remonta a mucho antes. \u00bfQuieres saber m\u00e1s sobre c\u00f3mo ha llegado a nuestros d\u00edas este dulce tan caracter\u00edstico? Contin\u00faa leyendo el art\u00edculo hasta el final para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7562,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[7],"tags":[],"class_list":["post-7560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"jetpack_featured_media_url":"https:\/\/pastisserialapalma.com\/wp-content\/uploads\/2022\/02\/como-nacio-el-bombon.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pastisserialapalma.com\/cat\/wp-json\/wp\/v2\/posts\/7560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pastisserialapalma.com\/cat\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pastisserialapalma.com\/cat\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pastisserialapalma.com\/cat\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pastisserialapalma.com\/cat\/wp-json\/wp\/v2\/comments?post=7560"}],"version-history":[{"count":0,"href":"https:\/\/pastisserialapalma.com\/cat\/wp-json\/wp\/v2\/posts\/7560\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pastisserialapalma.com\/cat\/wp-json\/wp\/v2\/media\/7562"}],"wp:attachment":[{"href":"https:\/\/pastisserialapalma.com\/cat\/wp-json\/wp\/v2\/media?parent=7560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pastisserialapalma.com\/cat\/wp-json\/wp\/v2\/categories?post=7560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pastisserialapalma.com\/cat\/wp-json\/wp\/v2\/tags?post=7560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}